{"id":477,"date":"2014-09-02T15:20:01","date_gmt":"2014-09-02T15:20:01","guid":{"rendered":"http:\/\/metzion.org\/heblog\/?p=477"},"modified":"2014-09-02T15:20:01","modified_gmt":"2014-09-02T15:20:01","slug":"%d7%a1%d7%93%d7%a8-%d7%a8%d7%90%d7%a9-%d7%94%d7%a9%d7%a0%d7%94-%d7%95%d7%90%d7%a8%d7%95%d7%97%d7%94-%d7%a7%d7%94%d7%99%d7%9c%d7%aa%d7%99%d7%aa-%d7%92%d7%95%d7%a8%d7%9e%d7%94-%d7%a2%d7%9d-%d7%91%d7%99","status":"publish","type":"post","link":"https:\/\/metzion.org\/heblog\/index.php\/477\/","title":{"rendered":"??? ??? ???? ?????? ??????? ????? ?? ???&#8221;? ????????? ??????!"},"content":{"rendered":"<div>\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"rtl\">\n<div dir=\"rtl\"><span style=\"color: #000099; font-size: medium;\">???? ??????? ???? ??? ???? ?? ?? ??????? ????????? ??????????? ????? ?????? ???? ?????? ???????! <\/p>\n","protected":false},"excerpt":{"rendered":"<p>???? ??????? ???? ??? ???? ?? ?? ??????? ????????? ??????????? ????? ?????? ???? ?????? ???????!<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[11,17,9,7,5],"tags":[],"_links":{"self":[{"href":"https:\/\/metzion.org\/heblog\/index.php\/wp-json\/wp\/v2\/posts\/477"}],"collection":[{"href":"https:\/\/metzion.org\/heblog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/metzion.org\/heblog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/metzion.org\/heblog\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/metzion.org\/heblog\/index.php\/wp-json\/wp\/v2\/comments?post=477"}],"version-history":[{"count":1,"href":"https:\/\/metzion.org\/heblog\/index.php\/wp-json\/wp\/v2\/posts\/477\/revisions"}],"predecessor-version":[{"id":479,"href":"https:\/\/metzion.org\/heblog\/index.php\/wp-json\/wp\/v2\/posts\/477\/revisions\/479"}],"wp:attachment":[{"href":"https:\/\/metzion.org\/heblog\/index.php\/wp-json\/wp\/v2\/media?parent=477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/metzion.org\/heblog\/index.php\/wp-json\/wp\/v2\/categories?post=477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/metzion.org\/heblog\/index.php\/wp-json\/wp\/v2\/tags?post=477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}